{"id":1988,"date":"2020-12-17T23:14:44","date_gmt":"2020-12-18T05:14:44","guid":{"rendered":"http:\/\/raxxie.com\/?p=1988"},"modified":"2020-12-17T23:14:44","modified_gmt":"2020-12-18T05:14:44","slug":"lista17","status":"publish","type":"post","link":"http:\/\/raxxie.com\/index.php\/archivo\/lista17\/","title":{"rendered":"Lista #17"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">10 caracter\u00edsticas que busco en un cuaderno<\/h2>\n\n\n\n<ol class=\"wp-block-list\"><li>Que el papel no sea demasiado delgado como para que se transparente de un lado al otro si uso pluma fuente o similar.<\/li><li>Mis gustos han ido cambiando. Un tiempo fui muy fan de la cuadr\u00edcula chica. Ahora los prefiero de rayas. Y enloquezco de alegr\u00eda cuando encuentro cuadr\u00edcula francesa (sey\u00e9s). Pero no me hago el feo a los cuadernos blancos ni a los doble raya. Eso s\u00ed: los de puntitos no me acaban de caer bien.<\/li><li>Que el cuaderno no sea muy grande: la forma francesa es mi favorita. Tambi\u00e9n me gusta mucho el tama\u00f1o de bolsillo cl\u00e1sico.<\/li><li>Hubo un tiempo en que me dio por las libretas con hojas de colores oscuros (ok: negras o moradas). Era lindo escribir con tinta blanca. Pero es un gorro para leer. As\u00ed que prefiero que sea papel color marfil, blanco o, ya aloc\u00e1ndonos, en colores tenues.<\/li><li>Prefiero que sean hojas cosidas. Segundo lugar: espiral met\u00e1lica.<\/li><li>Hojas cosidas, s\u00ed, pero que la libreta abra 180 grados sin deshojarse. Me chocan los cuadernos que no abren completo.<\/li><li>Me caen bien los que traen las hojas pre-cortadas (\u00bfo se dice \u00abdesprendibles\u00bb? Es que no me refiero a que sean tipo block).<\/li><li>Dibujitos tipo marca de agua, o en espacios no invasivos, s\u00ed. Que sean demasiado notorios o estorbosos, no. <\/li><li>El n\u00famero de p\u00e1ginas no importa. Lo mismo me gustan de 200 que de 80, con o sin separadores. <\/li><li>Si encima de todo eso pueden tener un dise\u00f1o de portada lindo, ya la hicimos. <\/li><li>Como pil\u00f3n: cuando encuentro todo eso en un cuaderno baratito, hasta ganas de llorar me dan, jeje.<\/li><\/ol>\n","protected":false},"excerpt":{"rendered":"<p>No es que sea yo la loca de las libretas, pero&#8230; ok, s\u00ed soy.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[33,95,35],"tags":[],"class_list":["post-1988","post","type-post","status-publish","format-standard","hentry","category-escritura","category-listas","category-vida-en-internet"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/sCt21-lista17","jetpack_sharing_enabled":true,"jetpack_likes_enabled":false,"_links":{"self":[{"href":"http:\/\/raxxie.com\/index.php\/wp-json\/wp\/v2\/posts\/1988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/raxxie.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/raxxie.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/raxxie.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/raxxie.com\/index.php\/wp-json\/wp\/v2\/comments?post=1988"}],"version-history":[{"count":1,"href":"http:\/\/raxxie.com\/index.php\/wp-json\/wp\/v2\/posts\/1988\/revisions"}],"predecessor-version":[{"id":1989,"href":"http:\/\/raxxie.com\/index.php\/wp-json\/wp\/v2\/posts\/1988\/revisions\/1989"}],"wp:attachment":[{"href":"http:\/\/raxxie.com\/index.php\/wp-json\/wp\/v2\/media?parent=1988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/raxxie.com\/index.php\/wp-json\/wp\/v2\/categories?post=1988"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/raxxie.com\/index.php\/wp-json\/wp\/v2\/tags?post=1988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}